
{"id":215,"date":"2015-05-31T21:38:07","date_gmt":"2015-05-31T19:38:07","guid":{"rendered":"https:\/\/www.tela-immobilien.de\/?page_id=215"},"modified":"2025-12-18T18:29:43","modified_gmt":"2025-12-18T16:29:43","slug":"angebote-mietimmobilien","status":"publish","type":"page","link":"https:\/\/www.tela-immobilien.de\/en\/angebote-mietimmobilien","title":{"rendered":"Offers: Rental properties"},"content":{"rendered":"<div id=\"fws_6a04a84b14b50\"  data-midnight=\"dark\"  data-bg-mobile-hidden=\"\" class=\"wpb_row vc_row-fluid vc_row top-level standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding\"  data-t-w-inherits=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"none\" data-border-style=\"solid\" data-border-color=\"\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\"><div class=\"column-bg-overlay\"><\/div>\n\t\t<div class=\"vc_column-inner\">\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div data-midnight=\"nectar-slider\" class=\"parallax_slider_outer\" style=\"min-height: 250px; \"><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"true\" data-animate-in-effect=\"none\" data-fullscreen=\"true\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"true\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap\" id=\"ns-id-6a04a84b14e36\" style=\"min-height: 250px; \"><div class=\"swiper-container\" style=\"min-height: 250px; \"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"false\" data-height=\"650\" data-min-height=\"250\" data-arrows=\"false\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"top\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" style=\"min-height: 250px; \"> \r\n\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.tela-immobilien.de\/wp-content\/uploads\/2015\/01\/paerchen_1600_700.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"content\"><h2>Offers: Rental properties<\/h2><\/div>\r\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading\"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \r\n\t\t\t\t\r\n\t\t\t<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04a84b15eb2\"  data-midnight=\"dark\"  data-bg-mobile-hidden=\"\" class=\"wpb_row vc_row-fluid vc_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding\"  data-t-w-inherits=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"none\" data-border-style=\"solid\" data-border-color=\"\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\"><div class=\"column-bg-overlay\"><\/div>\n\t\t<div class=\"vc_column-inner\">\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04a84b16284\"  data-midnight=\"dark\"  data-bg-mobile-hidden=\"\" class=\"wpb_row vc_row-fluid vc_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding\"  data-t-w-inherits=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"none\" data-border-style=\"solid\" data-border-color=\"\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\"><div class=\"column-bg-overlay\"><\/div>\n\t\t<div class=\"vc_column-inner\">\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n\t<div class=\"wpb_text_column wpb_content_element\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p class=\"translation-block\">You haven't found anything suitable in our portfolio? Then <a title=\"Vermittlung\" href=\"https:\/\/www.tela-immobilien.de\/en\/vermittlung\/\" target=\"_self\">let us find<\/a> a suitable property.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 50px;\" class=\"divider\"><\/div><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t\n\t<div id=\"immo-api-target\"><\/div>\t\n\t\n\t<script type=\"text\/javascript\">\n\t\t(function($){\n\t\t\t$(document).ready(function(){\n\t\t\t\t$.ajax({ url: \"https:\/\/www.tela-immobilien.de\/immobilienangebote_translate\/pages\/offer_index_api.php?t=rent&l=en\",\n\t\t\t\t\tcontext: document.body,\n\t\t\t\t\ttype: \"GET\",\n\t\t\t\t\tsuccess: function(response){\n\t\t\t\t\t\tvar content = response;\n\t\t\t\t\t\t$(\"#immo-api-target\").append(content);\n\t\t\t\t\t}});\n\t\t\t});\n\t\t})(jQuery);\n\t\t\n\t<\/script>\n\t\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/pages\/215"}],"collection":[{"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/comments?post=215"}],"version-history":[{"count":4,"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/pages\/215\/revisions"}],"predecessor-version":[{"id":462,"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/pages\/215\/revisions\/462"}],"wp:attachment":[{"href":"https:\/\/www.tela-immobilien.de\/en\/wp-json\/wp\/v2\/media?parent=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}